{"id":413,"date":"2024-02-13T00:57:57","date_gmt":"2024-02-13T00:57:57","guid":{"rendered":"https:\/\/diaespa.mx\/?post_type=product&#038;p=413"},"modified":"2024-02-23T06:49:36","modified_gmt":"2024-02-23T06:49:36","slug":"ultrasonido-portatil-de-3-mhz-con-fototerapia-7-colores","status":"publish","type":"product","link":"https:\/\/diaespa.mx\/index.php\/product\/ultrasonido-portatil-de-3-mhz-con-fototerapia-7-colores\/","title":{"rendered":"Ultrasonido port\u00e1til de 3 Mhz, con fototerapia 7 colores"},"content":{"rendered":"<p>Ideal para reabsorci\u00f3n de edemas y hematomas, tonificaci\u00f3n y aceleraci\u00f3n de los procesos cicatriciales. Es coadyuvante en el drenaje linf\u00e1tico, dolor agudo y cr\u00f3nico.<\/p>\n<p>Permite tratar la piel de la cara de manera muy eficiente, incluso el \u00e1rea de los ojos. Se recomienda el uso de este instrumento para disipar las ojeras y las bolsas de los ojos.<\/p>\n<p>Tambi\u00e9n se recomienda para la firmeza general de la cara, firmeza de la papada.<\/p>\n<p>Aumenta la absorci\u00f3n de nutrientes y medicamentos a m\u00e1s profundidad.<\/p>\n<p><strong>Caracter\u00edsticas:<\/strong><\/p>\n<p>-Programa en modo continuo.<br \/>\n-Tres programas de pulso.<br \/>\n-Cinco programas de intensidad.<br \/>\n-Cabeza de acero inoxidable.<br \/>\n-Terapia de fotones LED.<br \/>\n-7 colores terapia con fotones de luz roja, azul, p\u00farpura, amarillo, verde, turquesa y blanco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Descripci\u00f3n:<\/strong><\/p>\n<p>-Material: ABS.<br \/>\n-Salida: 15 V 1A.<br \/>\n-Potencia: 15W.<br \/>\n-Tiempo de tratamiento: 15 minutos a 1 hora.<br \/>\n-Color: blanco y negro.<br \/>\n-Tama\u00f1o: 17 cm (largo) * 7 cm (ancho) * 5 cm (alto).<\/p>\n","protected":false},"featured_media":397,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[40,23],"product_tag":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/product\/413"}],"collection":[{"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/comments?post=413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/media\/397"}],"wp:attachment":[{"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/media?parent=413"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/product_cat?post=413"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/diaespa.mx\/index.php\/wp-json\/wp\/v2\/product_tag?post=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}